{"id":41066,"date":"2023-09-14T11:12:31","date_gmt":"2023-09-14T11:12:31","guid":{"rendered":"https:\/\/www.ncheurope.com\/products\/industrial-maintenance-product\/kempt-lo\/"},"modified":"2023-09-14T11:12:31","modified_gmt":"2023-09-14T11:12:31","slug":"kempt-lo","status":"publish","type":"im_product","link":"https:\/\/www.ncheurope.com\/pt-pt\/products\/industrial-maintenance-product\/kempt-lo\/","title":{"rendered":"Kempt LO"},"author":1,"featured_media":49672,"parent":0,"template":"","meta":{"_acf_changed":false},"class_list":["post-41066","im_product","type-im_product","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.7 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Industrial Maintenance Products | NCH Europe<\/title>\n<meta name=\"description\" content=\"Explore how our extensive array of industrial maintenance products including degreasers, industrial cleaners &amp; rust treatments will fulfil your needs today.\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ncheurope.com\/en\/products\/industrial-maintenance-product\/kempt-lo\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Kempt LO\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Explore how our extensive array of industrial maintenance products including degreasers, industrial cleaners &amp; rust treatments will fulfil your needs today.\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ncheurope.com\/en\/products\/industrial-maintenance-product\/kempt-lo\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"NCH Europe\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ncheurope\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/09\/Placeholder.png\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:site\" content=\"@NCH_Europe\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/products\\\/industrial-maintenance-product\\\/kempt-lo\\\/\",\"url\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/products\\\/industrial-maintenance-product\\\/kempt-lo\\\/\",\"name\":\"Industrial Maintenance Products | NCH Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/products\\\/industrial-maintenance-product\\\/kempt-lo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/products\\\/industrial-maintenance-product\\\/kempt-lo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ncheurope.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Placeholder.png\",\"datePublished\":\"2023-09-14T11:12:31+00:00\",\"description\":\"Explore how our extensive array of industrial maintenance products including degreasers, industrial cleaners & rust treatments will fulfil your needs today.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/products\\\/industrial-maintenance-product\\\/kempt-lo\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/products\\\/industrial-maintenance-product\\\/kempt-lo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/products\\\/industrial-maintenance-product\\\/kempt-lo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ncheurope.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Placeholder.png\",\"contentUrl\":\"https:\\\/\\\/www.ncheurope.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Placeholder.png\",\"width\":200,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/products\\\/industrial-maintenance-product\\\/kempt-lo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"P\u00e1gina inicial\",\"item\":\"https:\\\/\\\/www.ncheurope.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Industrial Maintenance Products\",\"item\":\"https:\\\/\\\/www.ncheurope.com\\\/de\\\/products\\\/industrial-maintenance-products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kempt LO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/\",\"name\":\"NCH Europe\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#organization\",\"name\":\"NCH Europe\",\"url\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ncheurope.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/nch-logo-gradient.webp\",\"contentUrl\":\"https:\\\/\\\/www.ncheurope.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/nch-logo-gradient.webp\",\"width\":120,\"height\":120,\"caption\":\"NCH Europe\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ncheurope\",\"https:\\\/\\\/x.com\\\/NCH_Europe\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Industrial Maintenance Products | NCH Europe","description":"Explore how our extensive array of industrial maintenance products including degreasers, industrial cleaners & rust treatments will fulfil your needs today.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ncheurope.com\/en\/products\/industrial-maintenance-product\/kempt-lo\/","og_locale":"pt_PT","og_type":"article","og_title":"Kempt LO","og_description":"Explore how our extensive array of industrial maintenance products including degreasers, industrial cleaners & rust treatments will fulfil your needs today.","og_url":"https:\/\/www.ncheurope.com\/en\/products\/industrial-maintenance-product\/kempt-lo\/","og_site_name":"NCH Europe","article_publisher":"https:\/\/www.facebook.com\/ncheurope","og_image":[{"width":200,"height":200,"url":"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/09\/Placeholder.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@NCH_Europe","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ncheurope.com\/en\/products\/industrial-maintenance-product\/kempt-lo\/","url":"https:\/\/www.ncheurope.com\/en\/products\/industrial-maintenance-product\/kempt-lo\/","name":"Industrial Maintenance Products | NCH Europe","isPartOf":{"@id":"https:\/\/www.ncheurope.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ncheurope.com\/en\/products\/industrial-maintenance-product\/kempt-lo\/#primaryimage"},"image":{"@id":"https:\/\/www.ncheurope.com\/en\/products\/industrial-maintenance-product\/kempt-lo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/09\/Placeholder.png","datePublished":"2023-09-14T11:12:31+00:00","description":"Explore how our extensive array of industrial maintenance products including degreasers, industrial cleaners & rust treatments will fulfil your needs today.","breadcrumb":{"@id":"https:\/\/www.ncheurope.com\/en\/products\/industrial-maintenance-product\/kempt-lo\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ncheurope.com\/en\/products\/industrial-maintenance-product\/kempt-lo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.ncheurope.com\/en\/products\/industrial-maintenance-product\/kempt-lo\/#primaryimage","url":"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/09\/Placeholder.png","contentUrl":"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/09\/Placeholder.png","width":200,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.ncheurope.com\/en\/products\/industrial-maintenance-product\/kempt-lo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"P\u00e1gina inicial","item":"https:\/\/www.ncheurope.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Industrial Maintenance Products","item":"https:\/\/www.ncheurope.com\/de\/products\/industrial-maintenance-products\/"},{"@type":"ListItem","position":3,"name":"Kempt LO"}]},{"@type":"WebSite","@id":"https:\/\/www.ncheurope.com\/en\/#website","url":"https:\/\/www.ncheurope.com\/en\/","name":"NCH Europe","description":"","publisher":{"@id":"https:\/\/www.ncheurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ncheurope.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.ncheurope.com\/en\/#organization","name":"NCH Europe","url":"https:\/\/www.ncheurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.ncheurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/11\/nch-logo-gradient.webp","contentUrl":"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/11\/nch-logo-gradient.webp","width":120,"height":120,"caption":"NCH Europe"},"image":{"@id":"https:\/\/www.ncheurope.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ncheurope","https:\/\/x.com\/NCH_Europe"]}]}},"_links":{"self":[{"href":"https:\/\/www.ncheurope.com\/pt-pt\/wp-json\/wp\/v2\/im_product\/41066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ncheurope.com\/pt-pt\/wp-json\/wp\/v2\/im_product"}],"about":[{"href":"https:\/\/www.ncheurope.com\/pt-pt\/wp-json\/wp\/v2\/types\/im_product"}],"author":[{"embeddable":true,"href":"https:\/\/www.ncheurope.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.ncheurope.com\/pt-pt\/wp-json\/wp\/v2\/im_product\/41066\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ncheurope.com\/pt-pt\/wp-json\/wp\/v2\/media\/49672"}],"wp:attachment":[{"href":"https:\/\/www.ncheurope.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=41066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}