{"id":42538,"date":"2023-11-27T10:16:15","date_gmt":"2023-11-27T10:16:15","guid":{"rendered":"https:\/\/www.ncheurope.com\/thank-you-facilities\/"},"modified":"2024-07-17T14:33:17","modified_gmt":"2024-07-17T14:33:17","slug":"grazie-facilities","status":"publish","type":"page","link":"https:\/\/www.ncheurope.com\/it\/grazie-facilities\/","title":{"rendered":"Thank you"},"content":{"rendered":"\n<div class=\"internal-banner-block relative primaryBlue paddingBottomXLarge bg-no-repeat pt-[128px] bg-white bg-[url('assets\/images\/background-shape.png')] bg-right-bottom bg-contain\" >\n        <div class=\"container relative z-10\">\n        <div class=\"breadcrumb-container mb-[60px] md:mb-[103px] hidden md:block\">\n            <p class=\"text-darkXs !mb-0 !text-[12px] flex flex-row items-center\">You are here: <a class=\"!font-regular mx-2\" href=\"https:\/\/www.ncheurope.com\/it\/\">Home<\/a> \/ <span class=\"ml-2 font-semibold\">Thank you<\/span><\/p>\n        <\/div>\n\n        <div class=\"content-container flex flex-col-reverse md:flex-row flex-wrap justify-between\">\n\n                            <div class=\"text-container md:basis-8\/12\">\n                    <h1 class=\"heading-1 text-primaryBlue\">Grazie per aver contattato NCH Europe<\/h1>                    <p class=\"text-darkBase !mb-0\">Verrai contattato a breve da una persona del nostro team. Se hai bisogno di parlare con urgenza, consulta il nostro sito alla pagina \u201ccontattaci\u201d per trovare tutti i numeri di telefono e gli indirizzi e-mail. <\/p>                                            <a href=\"https:\/\/www.ncheurope.com\/it\/\" class=\"button button--primaryBlue mt-[32px]\">Torna alla homepage <\/a>\n                                    <\/div>\n            \n                    <\/div>\n    <\/div>\n<\/div>\n\n\n    <div class=\"related-cards-block box-content relative bg-white paddingTopLarge paddingBottomLarge primaryBlue\">\n        <div class=\"container flex flex-col\">\n            <!-- Start Text Section -->\n            <div class=\"flex flex-row flex-wrap justify-between items-end relative z-10 pb-[60px]\">\n                <h2 class=\"heading-2 basis-full text-primaryBlue\">Guarda le nostre applicazioni<\/h2>                <p class=\"text-darkBase basis-full lg:basis-8\/12 !mb-0\">Scopri di pi\u00f9 sulle soluzioni, sui prodotti e sui servizi disponibili in NCH Europe. Abbiamo un\u2019esperienza di oltre 100 anni nel fornire ai clienti le soluzioni di cui hanno bisogno, ad esempio per la manutenzione industriale, la gestione degli impianti, la pulizia dei pezzi e la lubrificazione di macchine e attrezzature. <\/p>                                    <a href=\"https:\/\/www.ncheurope.com\/it\/applicazioni\/\" class=\"button button--primaryBlue hover:bg-primaryBlue hover:text-white relative mt-[24px] lg:mt-0\">Esplora le nostre applicazioni<\/a>\n                            <\/div>\n            <!-- End Text Section -->\n            \n            <!-- Start Related Cards Section -->\n            \n                            <div class=\" flex flex-row flex-wrap\">\n                                                                        <div class=\"related-card max-w-full md:max-w-[calc(50%-4px)] lg:max-w-[calc(25%-8px)] w-full px-2 pt-2 pb-8 mr-0 md:odd:mr-2 lg:mr-2 mb-10 relative bg-white shadow-[0_10px_10px_0_rgba(109,106,112,0.15)] border border-primaryOffWhite\">\n                                <div class=\"blog-image relative bg-center bg-no-repeat bg-cover min-h-[216px] mb-6\" style=\"background-image: url('https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/07\/Maintenance-home.jpg')\"><\/div>\n                                <div class=\"flex flex-col items-start px-6\">\n                                    <h6 class=\"heading-6 text-primaryBlue z-10 relative !mb-4\">Maintenance <\/h6>\n                                    <p class=\"text-darkSm z-10 relative !mb-5\">Gli esperti della manutenzione industriale che assicurano un funzionamento efficace ed efficiente dei tuoi impianti e delle tue macchine con&hellip;<\/p>\n                                    <a href=\"https:\/\/www.ncheurope.com\/it\/applicazioni\/maintenance\/\" class=\"button button--secondary button--primaryBlue\">Maggiori informazioni<\/a>\n                                <\/div>\n                            <\/div>\n                                                                                                <div class=\"related-card max-w-full md:max-w-[calc(50%-4px)] lg:max-w-[calc(25%-8px)] w-full px-2 pt-2 pb-8 mr-0 md:odd:mr-2 lg:mr-2 mb-10 relative bg-white shadow-[0_10px_10px_0_rgba(109,106,112,0.15)] border border-primaryOffWhite\">\n                                <div class=\"blog-image relative bg-center bg-no-repeat bg-cover min-h-[216px] mb-6\" style=\"background-image: url('https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/07\/Facilities-home.jpg')\"><\/div>\n                                <div class=\"flex flex-col items-start px-6\">\n                                    <h6 class=\"heading-6 text-primaryBlue z-10 relative !mb-4\">Facilities <\/h6>\n                                    <p class=\"text-darkSm z-10 relative !mb-5\">Esperti nella gestione delle acque reflue e nel controllo degli odori nell\u2019hospitality e nell\u2019industria. Forniamo soluzioni sicure per l\u2019ambiente.<\/p>\n                                    <a href=\"https:\/\/www.ncheurope.com\/it\/applicazioni\/facilities\/\" class=\"button button--secondary button--primaryBlue\">Maggiori informazioni<\/a>\n                                <\/div>\n                            <\/div>\n                                                                                                <div class=\"related-card max-w-full md:max-w-[calc(50%-4px)] lg:max-w-[calc(25%-8px)] w-full px-2 pt-2 pb-8 mr-0 md:odd:mr-2 lg:mr-2 mb-10 relative bg-white shadow-[0_10px_10px_0_rgba(109,106,112,0.15)] border border-primaryOffWhite\">\n                                <div class=\"blog-image relative bg-center bg-no-repeat bg-cover min-h-[216px] mb-6\" style=\"background-image: url('https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/07\/Parts-Cleaning-home.jpg')\"><\/div>\n                                <div class=\"flex flex-col items-start px-6\">\n                                    <h6 class=\"heading-6 text-primaryBlue z-10 relative !mb-4\">Parts Cleaning<\/h6>\n                                    <p class=\"text-darkSm z-10 relative !mb-5\">Leader nei servizi per il trattamento, la pulizia e lo sgrassaggio delle superfici. Garantisce un&#8217;elevata produttivit\u00e0 e il rispetto dell\u2019ambiente.<\/p>\n                                    <a href=\"https:\/\/www.ncheurope.com\/it\/applicazioni\/parts-cleaning\/\" class=\"button button--secondary button--primaryBlue\">Maggiori informazioni<\/a>\n                                <\/div>\n                            <\/div>\n                                                                                                <div class=\"related-card max-w-full md:max-w-[calc(50%-4px)] lg:max-w-[calc(25%-8px)] w-full px-2 pt-2 pb-8 mr-0 md:odd:mr-2 lg:mr-2 mb-10 relative bg-white shadow-[0_10px_10px_0_rgba(109,106,112,0.15)] border border-primaryOffWhite\">\n                                <div class=\"blog-image relative bg-center bg-no-repeat bg-cover min-h-[216px] mb-6\" style=\"background-image: url('https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/07\/Lubricants-home.jpg')\"><\/div>\n                                <div class=\"flex flex-col items-start px-6\">\n                                    <h6 class=\"heading-6 text-primaryBlue z-10 relative !mb-4\">Lubricants <\/h6>\n                                    <p class=\"text-darkSm z-10 relative !mb-5\">Esperti dal 1948 nella tecnologia di lubrificazione pi\u00f9 innovativa. Forniamo grassi, oli e la tecnologia pi\u00f9 avanzata degli additivi.<\/p>\n                                    <a href=\"https:\/\/www.ncheurope.com\/it\/applicazioni\/lubricants\/\" class=\"button button--secondary button--primaryBlue\">Maggiori informazioni<\/a>\n                                <\/div>\n                            <\/div>\n                                                            <\/div>\n                        \n            <!-- End Related Cards Section -->\n        <\/div>\n\n    <\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-42538","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.7 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Thank you - NCH Europe<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Thank you\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ncheurope.com\/en\/thank-you-facilities\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"NCH Europe\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ncheurope\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-17T14:33:17+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:site\" content=\"@NCH_Europe\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/thank-you-facilities\\\/\",\"url\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/thank-you-facilities\\\/\",\"name\":\"Thank you - NCH Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#website\"},\"datePublished\":\"2023-11-27T10:16:15+00:00\",\"dateModified\":\"2024-07-17T14:33:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/thank-you-facilities\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/thank-you-facilities\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/thank-you-facilities\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/www.ncheurope.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Thank you\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/\",\"name\":\"NCH Europe\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#organization\",\"name\":\"NCH Europe\",\"url\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ncheurope.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/nch-logo-gradient.webp\",\"contentUrl\":\"https:\\\/\\\/www.ncheurope.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/nch-logo-gradient.webp\",\"width\":120,\"height\":120,\"caption\":\"NCH Europe\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ncheurope\",\"https:\\\/\\\/x.com\\\/NCH_Europe\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Thank you - NCH Europe","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Thank you","og_url":"https:\/\/www.ncheurope.com\/en\/thank-you-facilities\/","og_site_name":"NCH Europe","article_publisher":"https:\/\/www.facebook.com\/ncheurope","article_modified_time":"2024-07-17T14:33:17+00:00","twitter_card":"summary_large_image","twitter_site":"@NCH_Europe","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ncheurope.com\/en\/thank-you-facilities\/","url":"https:\/\/www.ncheurope.com\/en\/thank-you-facilities\/","name":"Thank you - NCH Europe","isPartOf":{"@id":"https:\/\/www.ncheurope.com\/en\/#website"},"datePublished":"2023-11-27T10:16:15+00:00","dateModified":"2024-07-17T14:33:17+00:00","breadcrumb":{"@id":"https:\/\/www.ncheurope.com\/en\/thank-you-facilities\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ncheurope.com\/en\/thank-you-facilities\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ncheurope.com\/en\/thank-you-facilities\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/www.ncheurope.com\/it\/"},{"@type":"ListItem","position":2,"name":"Thank you"}]},{"@type":"WebSite","@id":"https:\/\/www.ncheurope.com\/en\/#website","url":"https:\/\/www.ncheurope.com\/en\/","name":"NCH Europe","description":"","publisher":{"@id":"https:\/\/www.ncheurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ncheurope.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.ncheurope.com\/en\/#organization","name":"NCH Europe","url":"https:\/\/www.ncheurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ncheurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/11\/nch-logo-gradient.webp","contentUrl":"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/11\/nch-logo-gradient.webp","width":120,"height":120,"caption":"NCH Europe"},"image":{"@id":"https:\/\/www.ncheurope.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ncheurope","https:\/\/x.com\/NCH_Europe"]}]}},"_links":{"self":[{"href":"https:\/\/www.ncheurope.com\/it\/wp-json\/wp\/v2\/pages\/42538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ncheurope.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ncheurope.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ncheurope.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ncheurope.com\/it\/wp-json\/wp\/v2\/comments?post=42538"}],"version-history":[{"count":5,"href":"https:\/\/www.ncheurope.com\/it\/wp-json\/wp\/v2\/pages\/42538\/revisions"}],"predecessor-version":[{"id":54382,"href":"https:\/\/www.ncheurope.com\/it\/wp-json\/wp\/v2\/pages\/42538\/revisions\/54382"}],"wp:attachment":[{"href":"https:\/\/www.ncheurope.com\/it\/wp-json\/wp\/v2\/media?parent=42538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}