{"id":50375,"date":"2023-09-14T11:11:25","date_gmt":"2023-09-14T11:11:25","guid":{"rendered":"https:\/\/www.ncheurope.com\/products\/industrial-maintenance-product\/full-back-c\/"},"modified":"2024-06-06T07:38:08","modified_gmt":"2024-06-06T07:38:08","slug":"full-back-c","status":"publish","type":"im_product","link":"https:\/\/www.ncheurope.com\/el\/products\/industrial-maintenance-product\/full-back-c\/","title":{"rendered":"Full Back C"},"author":1,"featured_media":49667,"parent":0,"template":"","meta":{"_acf_changed":false},"class_list":["post-50375","im_product","type-im_product","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.7 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Industrial Maintenance Products | NCH Europe<\/title>\n<meta name=\"description\" content=\"Explore how our extensive array of industrial maintenance products including degreasers, industrial cleaners &amp; rust treatments will fulfil your needs today.\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ncheurope.com\/el\/products\/industrial-maintenance-product\/full-back-c-2\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"el_GR\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Full Back C\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Explore how our extensive array of industrial maintenance products including degreasers, industrial cleaners &amp; rust treatments will fulfil your needs today.\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ncheurope.com\/el\/products\/industrial-maintenance-product\/full-back-c-2\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"NCH Europe\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ncheurope\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-06T07:38:08+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/09\/Placeholder.png\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:site\" content=\"@NCH_Europe\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/el\\\/products\\\/industrial-maintenance-product\\\/full-back-c-2\\\/\",\"url\":\"https:\\\/\\\/www.ncheurope.com\\\/el\\\/products\\\/industrial-maintenance-product\\\/full-back-c-2\\\/\",\"name\":\"Industrial Maintenance Products | NCH Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/el\\\/products\\\/industrial-maintenance-product\\\/full-back-c-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/el\\\/products\\\/industrial-maintenance-product\\\/full-back-c-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ncheurope.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Placeholder.png\",\"datePublished\":\"2023-09-14T11:11:25+00:00\",\"dateModified\":\"2024-06-06T07:38:08+00:00\",\"description\":\"Explore how our extensive array of industrial maintenance products including degreasers, industrial cleaners & rust treatments will fulfil your needs today.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/el\\\/products\\\/industrial-maintenance-product\\\/full-back-c-2\\\/#breadcrumb\"},\"inLanguage\":\"el\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ncheurope.com\\\/el\\\/products\\\/industrial-maintenance-product\\\/full-back-c-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/el\\\/products\\\/industrial-maintenance-product\\\/full-back-c-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ncheurope.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Placeholder.png\",\"contentUrl\":\"https:\\\/\\\/www.ncheurope.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Placeholder.png\",\"width\":200,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/el\\\/products\\\/industrial-maintenance-product\\\/full-back-c-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hemsida\",\"item\":\"https:\\\/\\\/www.ncheurope.com\\\/el\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Industrial Maintenance Products\",\"item\":\"https:\\\/\\\/www.ncheurope.com\\\/de\\\/products\\\/industrial-maintenance-products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Full Back C\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/\",\"name\":\"NCH Europe\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"el\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#organization\",\"name\":\"NCH Europe\",\"url\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ncheurope.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/nch-logo-gradient.webp\",\"contentUrl\":\"https:\\\/\\\/www.ncheurope.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/nch-logo-gradient.webp\",\"width\":120,\"height\":120,\"caption\":\"NCH Europe\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ncheurope\",\"https:\\\/\\\/x.com\\\/NCH_Europe\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Industrial Maintenance Products | NCH Europe","description":"Explore how our extensive array of industrial maintenance products including degreasers, industrial cleaners & rust treatments will fulfil your needs today.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ncheurope.com\/el\/products\/industrial-maintenance-product\/full-back-c-2\/","og_locale":"el_GR","og_type":"article","og_title":"Full Back C","og_description":"Explore how our extensive array of industrial maintenance products including degreasers, industrial cleaners & rust treatments will fulfil your needs today.","og_url":"https:\/\/www.ncheurope.com\/el\/products\/industrial-maintenance-product\/full-back-c-2\/","og_site_name":"NCH Europe","article_publisher":"https:\/\/www.facebook.com\/ncheurope","article_modified_time":"2024-06-06T07:38:08+00:00","og_image":[{"width":200,"height":200,"url":"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/09\/Placeholder.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@NCH_Europe","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ncheurope.com\/el\/products\/industrial-maintenance-product\/full-back-c-2\/","url":"https:\/\/www.ncheurope.com\/el\/products\/industrial-maintenance-product\/full-back-c-2\/","name":"Industrial Maintenance Products | NCH Europe","isPartOf":{"@id":"https:\/\/www.ncheurope.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ncheurope.com\/el\/products\/industrial-maintenance-product\/full-back-c-2\/#primaryimage"},"image":{"@id":"https:\/\/www.ncheurope.com\/el\/products\/industrial-maintenance-product\/full-back-c-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/09\/Placeholder.png","datePublished":"2023-09-14T11:11:25+00:00","dateModified":"2024-06-06T07:38:08+00:00","description":"Explore how our extensive array of industrial maintenance products including degreasers, industrial cleaners & rust treatments will fulfil your needs today.","breadcrumb":{"@id":"https:\/\/www.ncheurope.com\/el\/products\/industrial-maintenance-product\/full-back-c-2\/#breadcrumb"},"inLanguage":"el","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ncheurope.com\/el\/products\/industrial-maintenance-product\/full-back-c-2\/"]}]},{"@type":"ImageObject","inLanguage":"el","@id":"https:\/\/www.ncheurope.com\/el\/products\/industrial-maintenance-product\/full-back-c-2\/#primaryimage","url":"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/09\/Placeholder.png","contentUrl":"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/09\/Placeholder.png","width":200,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.ncheurope.com\/el\/products\/industrial-maintenance-product\/full-back-c-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hemsida","item":"https:\/\/www.ncheurope.com\/el\/"},{"@type":"ListItem","position":2,"name":"Industrial Maintenance Products","item":"https:\/\/www.ncheurope.com\/de\/products\/industrial-maintenance-products\/"},{"@type":"ListItem","position":3,"name":"Full Back C"}]},{"@type":"WebSite","@id":"https:\/\/www.ncheurope.com\/en\/#website","url":"https:\/\/www.ncheurope.com\/en\/","name":"NCH Europe","description":"","publisher":{"@id":"https:\/\/www.ncheurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ncheurope.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"el"},{"@type":"Organization","@id":"https:\/\/www.ncheurope.com\/en\/#organization","name":"NCH Europe","url":"https:\/\/www.ncheurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"el","@id":"https:\/\/www.ncheurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/11\/nch-logo-gradient.webp","contentUrl":"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/11\/nch-logo-gradient.webp","width":120,"height":120,"caption":"NCH Europe"},"image":{"@id":"https:\/\/www.ncheurope.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ncheurope","https:\/\/x.com\/NCH_Europe"]}]}},"_links":{"self":[{"href":"https:\/\/www.ncheurope.com\/el\/wp-json\/wp\/v2\/im_product\/50375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ncheurope.com\/el\/wp-json\/wp\/v2\/im_product"}],"about":[{"href":"https:\/\/www.ncheurope.com\/el\/wp-json\/wp\/v2\/types\/im_product"}],"author":[{"embeddable":true,"href":"https:\/\/www.ncheurope.com\/el\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/www.ncheurope.com\/el\/wp-json\/wp\/v2\/im_product\/50375\/revisions"}],"predecessor-version":[{"id":52977,"href":"https:\/\/www.ncheurope.com\/el\/wp-json\/wp\/v2\/im_product\/50375\/revisions\/52977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ncheurope.com\/el\/wp-json\/wp\/v2\/media\/49667"}],"wp:attachment":[{"href":"https:\/\/www.ncheurope.com\/el\/wp-json\/wp\/v2\/media?parent=50375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}