{"id":44828,"date":"2023-09-14T11:11:25","date_gmt":"2023-09-14T11:11:25","guid":{"rendered":"https:\/\/www.ncheurope.com\/products\/industrial-maintenance-product\/lexite-extra\/"},"modified":"2023-09-14T11:11:25","modified_gmt":"2023-09-14T11:11:25","slug":"lexite-extra","status":"publish","type":"im_product","link":"https:\/\/www.ncheurope.com\/de\/products\/industrial-maintenance-product\/lexite-extra\/","title":{"rendered":"Lexite Extra"},"author":1,"featured_media":64309,"parent":0,"template":"","meta":{"_acf_changed":false},"class_list":["post-44828","im_product","type-im_product","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.7 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Industrial Maintenance Products | NCH Europe<\/title>\n<meta name=\"description\" content=\"Explore how our extensive array of industrial maintenance products including degreasers, industrial cleaners &amp; rust treatments will fulfil your needs today.\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ncheurope.com\/de\/products\/industrial-maintenance-product\/lexite-extra\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Lexite Extra\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Explore how our extensive array of industrial maintenance products including degreasers, industrial cleaners &amp; rust treatments will fulfil your needs today.\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ncheurope.com\/de\/products\/industrial-maintenance-product\/lexite-extra\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"NCH Europe\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ncheurope\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/07\/Lexite-Extra-dual-straw-featured-image-420x1024.png\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"420\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:site\" content=\"@NCH_Europe\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/de\\\/products\\\/industrial-maintenance-product\\\/lexite-extra\\\/\",\"url\":\"https:\\\/\\\/www.ncheurope.com\\\/de\\\/products\\\/industrial-maintenance-product\\\/lexite-extra\\\/\",\"name\":\"Industrial Maintenance Products | NCH Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/de\\\/products\\\/industrial-maintenance-product\\\/lexite-extra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/de\\\/products\\\/industrial-maintenance-product\\\/lexite-extra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ncheurope.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Lexite-Extra-aerosol-1.png\",\"datePublished\":\"2023-09-14T11:11:25+00:00\",\"description\":\"Explore how our extensive array of industrial maintenance products including degreasers, industrial cleaners & rust treatments will fulfil your needs today.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/de\\\/products\\\/industrial-maintenance-product\\\/lexite-extra\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ncheurope.com\\\/de\\\/products\\\/industrial-maintenance-product\\\/lexite-extra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/de\\\/products\\\/industrial-maintenance-product\\\/lexite-extra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ncheurope.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Lexite-Extra-aerosol-1.png\",\"contentUrl\":\"https:\\\/\\\/www.ncheurope.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Lexite-Extra-aerosol-1.png\",\"width\":1086,\"height\":2778,\"caption\":\"Isolated aerosol product with name name and logo on label.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/de\\\/products\\\/industrial-maintenance-product\\\/lexite-extra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.ncheurope.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Industrial Maintenance Products\",\"item\":\"https:\\\/\\\/www.ncheurope.com\\\/de\\\/products\\\/industrial-maintenance-products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lexite Extra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/\",\"name\":\"NCH Europe\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#organization\",\"name\":\"NCH Europe\",\"url\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ncheurope.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/nch-logo-gradient.webp\",\"contentUrl\":\"https:\\\/\\\/www.ncheurope.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/nch-logo-gradient.webp\",\"width\":120,\"height\":120,\"caption\":\"NCH Europe\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ncheurope.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ncheurope\",\"https:\\\/\\\/x.com\\\/NCH_Europe\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Industrial Maintenance Products | NCH Europe","description":"Explore how our extensive array of industrial maintenance products including degreasers, industrial cleaners & rust treatments will fulfil your needs today.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ncheurope.com\/de\/products\/industrial-maintenance-product\/lexite-extra\/","og_locale":"de_DE","og_type":"article","og_title":"Lexite Extra","og_description":"Explore how our extensive array of industrial maintenance products including degreasers, industrial cleaners & rust treatments will fulfil your needs today.","og_url":"https:\/\/www.ncheurope.com\/de\/products\/industrial-maintenance-product\/lexite-extra\/","og_site_name":"NCH Europe","article_publisher":"https:\/\/www.facebook.com\/ncheurope","og_image":[{"width":420,"height":1024,"url":"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/07\/Lexite-Extra-dual-straw-featured-image-420x1024.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@NCH_Europe","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ncheurope.com\/de\/products\/industrial-maintenance-product\/lexite-extra\/","url":"https:\/\/www.ncheurope.com\/de\/products\/industrial-maintenance-product\/lexite-extra\/","name":"Industrial Maintenance Products | NCH Europe","isPartOf":{"@id":"https:\/\/www.ncheurope.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ncheurope.com\/de\/products\/industrial-maintenance-product\/lexite-extra\/#primaryimage"},"image":{"@id":"https:\/\/www.ncheurope.com\/de\/products\/industrial-maintenance-product\/lexite-extra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/09\/Lexite-Extra-aerosol-1.png","datePublished":"2023-09-14T11:11:25+00:00","description":"Explore how our extensive array of industrial maintenance products including degreasers, industrial cleaners & rust treatments will fulfil your needs today.","breadcrumb":{"@id":"https:\/\/www.ncheurope.com\/de\/products\/industrial-maintenance-product\/lexite-extra\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ncheurope.com\/de\/products\/industrial-maintenance-product\/lexite-extra\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.ncheurope.com\/de\/products\/industrial-maintenance-product\/lexite-extra\/#primaryimage","url":"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/09\/Lexite-Extra-aerosol-1.png","contentUrl":"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/09\/Lexite-Extra-aerosol-1.png","width":1086,"height":2778,"caption":"Isolated aerosol product with name name and logo on label."},{"@type":"BreadcrumbList","@id":"https:\/\/www.ncheurope.com\/de\/products\/industrial-maintenance-product\/lexite-extra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.ncheurope.com\/de\/"},{"@type":"ListItem","position":2,"name":"Industrial Maintenance Products","item":"https:\/\/www.ncheurope.com\/de\/products\/industrial-maintenance-products\/"},{"@type":"ListItem","position":3,"name":"Lexite Extra"}]},{"@type":"WebSite","@id":"https:\/\/www.ncheurope.com\/en\/#website","url":"https:\/\/www.ncheurope.com\/en\/","name":"NCH Europe","description":"","publisher":{"@id":"https:\/\/www.ncheurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ncheurope.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.ncheurope.com\/en\/#organization","name":"NCH Europe","url":"https:\/\/www.ncheurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.ncheurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/11\/nch-logo-gradient.webp","contentUrl":"https:\/\/www.ncheurope.com\/wp-content\/uploads\/2023\/11\/nch-logo-gradient.webp","width":120,"height":120,"caption":"NCH Europe"},"image":{"@id":"https:\/\/www.ncheurope.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ncheurope","https:\/\/x.com\/NCH_Europe"]}]}},"_links":{"self":[{"href":"https:\/\/www.ncheurope.com\/de\/wp-json\/wp\/v2\/im_product\/44828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ncheurope.com\/de\/wp-json\/wp\/v2\/im_product"}],"about":[{"href":"https:\/\/www.ncheurope.com\/de\/wp-json\/wp\/v2\/types\/im_product"}],"author":[{"embeddable":true,"href":"https:\/\/www.ncheurope.com\/de\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.ncheurope.com\/de\/wp-json\/wp\/v2\/im_product\/44828\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ncheurope.com\/de\/wp-json\/wp\/v2\/media\/64309"}],"wp:attachment":[{"href":"https:\/\/www.ncheurope.com\/de\/wp-json\/wp\/v2\/media?parent=44828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}